{"id":94204,"date":"2026-07-15T14:23:13","date_gmt":"2026-07-15T17:23:13","guid":{"rendered":"https:\/\/radiolarioja.com.ar\/rlr\/?p=94204"},"modified":"2026-07-15T14:23:14","modified_gmt":"2026-07-15T17:23:14","slug":"primera-mesa-de-trabajo-con-el-sector-cientifico-industrial-y-productivo-de-la-provincia-organizado-por-la-fundacion-barcelo","status":"publish","type":"post","link":"https:\/\/radiolarioja.com.ar\/rlr\/primera-mesa-de-trabajo-con-el-sector-cientifico-industrial-y-productivo-de-la-provincia-organizado-por-la-fundacion-barcelo\/","title":{"rendered":"Primera\u00a0Mesa de Trabajo con el sector cient\u00edfico, industrial y productivo de la provincia, organizado por la Fundaci\u00f3n Barcel\u00f3"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>La Rioja, julio 2026 &#8211;<\/strong>&nbsp;&nbsp;La Fundaci\u00f3n Barcel\u00f3 realiz\u00f3 en su sede La Rioja la primera&nbsp;<strong>Mesa de Trabajo con el sector cient\u00edfico, industrial y productivo de la provincia<\/strong>, un espacio de di\u00e1logo que reuni\u00f3 a representantes del sector empresarial, organismos del Gobierno provincial y autoridades acad\u00e9micas para acercar la formaci\u00f3n universitaria a las necesidades del mundo del trabajo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El encuentro fue encabezado por el decano de Fundaci\u00f3n Barcel\u00f3, Dr. Ricardo Znaidak; la secretaria acad\u00e9mica, Lic. Valeria Altieri; el coordinador general de la sede La Rioja, Lic. Fabi\u00e1n Calder\u00f3n; el vicedecano de la sede La Rioja, Dr. Le\u00f3n Malamud y la secretaria acad\u00e9mica de la sede La Rioja, Dra. Ana Costa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la jornada, los participantes compartieron su visi\u00f3n sobre los principales desaf\u00edos que atraviesan hoy las empresas y el entramado productivo riojano. La conversaci\u00f3n gir\u00f3 en torno a temas como la formaci\u00f3n de recursos humanos, la incorporaci\u00f3n de nuevas competencias, la sostenibilidad, la log\u00edstica y las oportunidades de desarrollo que presenta la provincia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u00abCuando hablamos de acercar la formaci\u00f3n universitaria al mundo del trabajo, hablamos de esto: escuchar a quienes producen, invierten y generan empleo en La Rioja\u201d,<\/em>&nbsp;se\u00f1al\u00f3 el coordinador general de Fundaci\u00f3n Barcel\u00f3 Sede La Rioja, Lic. Fabi\u00e1n Calder\u00f3n.&nbsp;<em>\u201cConocer qu\u00e9 necesitan hoy las empresas nos permite pensar una formaci\u00f3n cada vez m\u00e1s conectada con las necesidades de la provincia y la regi\u00f3n\u00bb<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Participaron de la mesa de trabajo representantes de la Secretar\u00eda de Ciencia y Tecnolog\u00eda de la provincia, la Secretar\u00eda de Miner\u00eda, la C\u00e1mara Empresarial Riojana (CER), la Uni\u00f3n de Industrias Riojanas (UNIR), Parque E\u00f3lico Arauco, Laboratorios Beta, Tetra Pak, QUILPE S. A. y la C\u00e1mara Oliv\u00edcola de La Rioja, entre otras instituciones y empresas de la provincia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta iniciativa se enmarca en el trabajo que la Fundaci\u00f3n Barcel\u00f3 viene desarrollando para fortalecer el v\u00ednculo con el sector productivo, identificar necesidades concretas y generar respuestas desde la formaci\u00f3n, la investigaci\u00f3n y la vinculaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El encuentro permiti\u00f3 identificar temas comunes y abrir un espacio de di\u00e1logo, para seguir formando profesionales que respondan a las transformaciones del mundo laboral actual y acompa\u00f1en el desarrollo de La Rioja y la regi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Acerca de Fundaci\u00f3n Barcel\u00f3<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Fundaci\u00f3n Barcel\u00f3 es sin\u00f3nimo de conocimientos acad\u00e9micos, cient\u00edficos y de transmisi\u00f3n de valores, orientados a la formaci\u00f3n de profesionales comprometidos e involucrados con la problem\u00e1tica actual en el campo de la salud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ubicaci\u00f3n estrat\u00e9gica de sus tres sedes: Buenos Aires, La Rioja y Santo Tom\u00e9 (Corrientes), brinda una experiencia educativa \u00fanica, en la que los alumnos pueden tomar contacto con diferentes realidades sociales y sanitarias, as\u00ed como conocer las particularidades del sistema de salud argentino.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo a los requisitos establecidos a nivel nacional, todas las carreras se encuentran aprobadas por resoluci\u00f3n ministerial, y acreditadas ante la CONEAU en los casos correspondientes. Adem\u00e1s de los cursos a distancia y extensi\u00f3n universitaria que, complementados con los convenios con hospitales, universidades y otras instituciones ofrecen una amplia y enriquecedora propuesta educativa para los futuros y actuales profesionales de la salud.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Rioja, julio 2026 &#8211;&nbsp;&nbsp;La Fundaci\u00f3n Barcel\u00f3 realiz\u00f3 en su sede La Rioja la primera&nbsp;Mesa de Trabajo con el sector cient\u00edfico, industrial y productivo de la provincia, un espacio de di\u00e1logo que reuni\u00f3 a representantes del sector empresarial, organismos del Gobierno provincial y autoridades acad\u00e9micas para acercar la formaci\u00f3n universitaria a las necesidades del mundo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":94205,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[12],"tags":[],"class_list":["post-94204","post","type-post","status-publish","format-standard","has-post-thumbnail","category-local"],"featured_image_urls":{"full":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/2026-07-14-Fundacion-Barcelo.-Mesa-de-Trabajo-con-el-sector-productivo-La-Rioja-1-scaled.jpg",2560,1182,false],"thumbnail":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/2026-07-14-Fundacion-Barcelo.-Mesa-de-Trabajo-con-el-sector-productivo-La-Rioja-1-150x150.jpg",150,150,true],"medium":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/2026-07-14-Fundacion-Barcelo.-Mesa-de-Trabajo-con-el-sector-productivo-La-Rioja-1-300x139.jpg",300,139,true],"medium_large":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/2026-07-14-Fundacion-Barcelo.-Mesa-de-Trabajo-con-el-sector-productivo-La-Rioja-1-768x355.jpg",696,322,true],"large":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/2026-07-14-Fundacion-Barcelo.-Mesa-de-Trabajo-con-el-sector-productivo-La-Rioja-1-1024x473.jpg",696,321,true],"1536x1536":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/2026-07-14-Fundacion-Barcelo.-Mesa-de-Trabajo-con-el-sector-productivo-La-Rioja-1-1536x709.jpg",1536,709,true],"2048x2048":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/2026-07-14-Fundacion-Barcelo.-Mesa-de-Trabajo-con-el-sector-productivo-La-Rioja-1-2048x946.jpg",2048,946,true],"td_218x150":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/2026-07-14-Fundacion-Barcelo.-Mesa-de-Trabajo-con-el-sector-productivo-La-Rioja-1-218x150.jpg",218,150,true],"td_324x400":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/2026-07-14-Fundacion-Barcelo.-Mesa-de-Trabajo-con-el-sector-productivo-La-Rioja-1-324x400.jpg",324,400,true],"td_485x360":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/2026-07-14-Fundacion-Barcelo.-Mesa-de-Trabajo-con-el-sector-productivo-La-Rioja-1-485x360.jpg",485,360,true],"td_696x0":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/2026-07-14-Fundacion-Barcelo.-Mesa-de-Trabajo-con-el-sector-productivo-La-Rioja-1-696x321.jpg",696,321,true],"td_1068x0":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/2026-07-14-Fundacion-Barcelo.-Mesa-de-Trabajo-con-el-sector-productivo-La-Rioja-1-1068x493.jpg",1068,493,true],"td_1920x0":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/2026-07-14-Fundacion-Barcelo.-Mesa-de-Trabajo-con-el-sector-productivo-La-Rioja-1-1920x887.jpg",1920,887,true],"td_0x420":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/2026-07-14-Fundacion-Barcelo.-Mesa-de-Trabajo-con-el-sector-productivo-La-Rioja-1-910x420.jpg",910,420,true],"td_80x60":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/2026-07-14-Fundacion-Barcelo.-Mesa-de-Trabajo-con-el-sector-productivo-La-Rioja-1-80x60.jpg",80,60,true],"td_100x70":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/2026-07-14-Fundacion-Barcelo.-Mesa-de-Trabajo-con-el-sector-productivo-La-Rioja-1-100x70.jpg",100,70,true],"td_265x198":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/2026-07-14-Fundacion-Barcelo.-Mesa-de-Trabajo-con-el-sector-productivo-La-Rioja-1-265x198.jpg",265,198,true],"td_324x160":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/2026-07-14-Fundacion-Barcelo.-Mesa-de-Trabajo-con-el-sector-productivo-La-Rioja-1-324x160.jpg",324,160,true],"td_324x235":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/2026-07-14-Fundacion-Barcelo.-Mesa-de-Trabajo-con-el-sector-productivo-La-Rioja-1-324x235.jpg",324,235,true],"td_356x220":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/2026-07-14-Fundacion-Barcelo.-Mesa-de-Trabajo-con-el-sector-productivo-La-Rioja-1-356x220.jpg",356,220,true],"td_356x364":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/2026-07-14-Fundacion-Barcelo.-Mesa-de-Trabajo-con-el-sector-productivo-La-Rioja-1-356x364.jpg",356,364,true],"td_533x261":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/2026-07-14-Fundacion-Barcelo.-Mesa-de-Trabajo-con-el-sector-productivo-La-Rioja-1-533x261.jpg",533,261,true],"td_534x462":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/2026-07-14-Fundacion-Barcelo.-Mesa-de-Trabajo-con-el-sector-productivo-La-Rioja-1-534x462.jpg",534,462,true],"td_696x385":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/2026-07-14-Fundacion-Barcelo.-Mesa-de-Trabajo-con-el-sector-productivo-La-Rioja-1-696x385.jpg",696,385,true],"td_741x486":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/2026-07-14-Fundacion-Barcelo.-Mesa-de-Trabajo-con-el-sector-productivo-La-Rioja-1-741x486.jpg",741,486,true],"td_1068x580":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/2026-07-14-Fundacion-Barcelo.-Mesa-de-Trabajo-con-el-sector-productivo-La-Rioja-1-1068x580.jpg",1068,580,true]},"author_info":{"info":["RadioLaRioja"]},"category_info":"<a href=\"https:\/\/radiolarioja.com.ar\/rlr\/category\/local\/\" rel=\"category tag\">Local<\/a>","tag_info":"Local","comment_count":"0","_links":{"self":[{"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/posts\/94204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/comments?post=94204"}],"version-history":[{"count":1,"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/posts\/94204\/revisions"}],"predecessor-version":[{"id":94206,"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/posts\/94204\/revisions\/94206"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/media\/94205"}],"wp:attachment":[{"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/media?parent=94204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/categories?post=94204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/tags?post=94204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}