{"id":94071,"date":"2026-07-14T20:16:02","date_gmt":"2026-07-14T23:16:02","guid":{"rendered":"https:\/\/radiolarioja.com.ar\/rlr\/?p=94071"},"modified":"2026-07-14T20:16:04","modified_gmt":"2026-07-14T23:16:04","slug":"humanizar-los-datos-el-ministerio-de-salud-presento-los-avances-del-plan-provincial-de-salud-2030","status":"publish","type":"post","link":"https:\/\/radiolarioja.com.ar\/rlr\/humanizar-los-datos-el-ministerio-de-salud-presento-los-avances-del-plan-provincial-de-salud-2030\/","title":{"rendered":"Humanizar los datos: el Ministerio de Salud present\u00f3 los avances del Plan Provincial de Salud 2030"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Feria del Libro<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el marco de la XXIII Feria del Libro de La Rioja, el Ministerio de Salud present\u00f3 los avances del Plan Provincial de Salud 2030 a trav\u00e9s de la conferencia \u00abLa humanizaci\u00f3n del dato para transformar la gesti\u00f3n p\u00fablica\u00bb, un espacio de intercambio en el que se expusieron las estrategias que se desarrollan en toda la provincia para fortalecer la planificaci\u00f3n sanitaria, ampliar el acceso a la salud y consolidar pol\u00edticas p\u00fablicas centradas en las personas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La actividad estuvo encabezada por el ministro de Salud, Juan Carlos Vergara, junto la coordinadora Ejecutiva del Plan Provincial Romina Cuello y la Subsecretaria de Planificaci\u00f3n Estrat\u00e9gica y Monitoreo Laura Zapata, quienes expusieron c\u00f3mo el uso estrat\u00e9gico de la informaci\u00f3n permite anticipar necesidades, definir prioridades y brindar respuestas oportunas a cada comunidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la apertura, Vergara destac\u00f3 que el Plan contin\u00faa consolid\u00e1ndose como una pol\u00edtica p\u00fablica que orienta la gesti\u00f3n sanitaria con una mirada integral, sustentada en informaci\u00f3n de calidad, planificaci\u00f3n y un fuerte trabajo territorial. En ese sentido, remarc\u00f3 que cada decisi\u00f3n debe tener como prioridad mejorar el acceso y la calidad de la atenci\u00f3n para todas y todos los riojanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, Vergara explic\u00f3 que uno de los principales objetivos de la conferencia fue acercar a la comunidad el proceso de transformaci\u00f3n que impulsa el Ministerio y mostrar c\u00f3mo los datos se convierten en una herramienta para mejorar la salud de la poblaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEs muy importante presentarlo para que toda la comunidad lo conozca, para que sepa qu\u00e9 estamos haciendo y que se vea que hay una decisi\u00f3n del Estado, del Gobierno, de humanizar los datos, no solamente en conseguir m\u00e1s informaci\u00f3n, sino que esa informaci\u00f3n la podamos poner al servicio de la comunidad y poder tomar las decisiones tambi\u00e9n de manera humana\u00bb, afirm\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte Romina Cuello se\u00f1al\u00f3 adem\u00e1s que esta estrategia ya se implementa en distintos departamentos de la provincia. Explic\u00f3 que las primeras acciones se concentraron en Capital por su densidad poblacional, aunque actualmente el trabajo se extiende al interior para llegar a m\u00e1s comunidades con una l\u00f3gica preventiva y cercana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEstamos trabajando en el interior para llegar a m\u00e1s comunidades y que esas comunidades se sientan realmente cuidadas. La idea del plan es pasar a una pol\u00edtica p\u00fablica proactiva, donde se busque a las personas y se llegue a cada una de ellas para brindarles la respuesta que necesiten\u00bb, expres\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tanto, la subsecretaria de Planificaci\u00f3n Estrat\u00e9gica y Monitoreo, Laura Zapata, sostuvo que humanizar los datos significa comprender que detr\u00e1s de cada indicador hay personas con necesidades concretas. En ese sentido, afirm\u00f3 que el desaf\u00edo del sistema sanitario es identificar tanto a quienes ya reciben atenci\u00f3n como a quienes a\u00fan no han sido alcanzados por las estrategias de cuidado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abDetr\u00e1s de cada porcentaje, detr\u00e1s de cada n\u00famero hay personas. Lo que nos interesa es reflexionar con los equipos de salud sobre aquellas personas a las que llegamos, pero sobre todo sobre las que todav\u00eda no llegamos. Hoy estamos en muchas mejores condiciones gracias a los sistemas de informaci\u00f3n para que los equipos de salud conozcan qui\u00e9nes necesitan determinados cuidados y puedan planificar sus acciones de manera m\u00e1s organizada y priorizada\u00bb, sostuvo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De esta manera, la conferencia permiti\u00f3 mostrar c\u00f3mo la informaci\u00f3n deja de ser un conjunto de estad\u00edsticas para convertirse en una herramienta de gesti\u00f3n que orienta decisiones, prioriza intervenciones y fortalece pol\u00edticas p\u00fablicas m\u00e1s cercanas a la realidad de cada riojana y riojano. Ese es el esp\u00edritu del Plan Provincial de Salud 2030: humanizar los datos para construir un sistema sanitario que llegue antes, mejor y a quienes m\u00e1s lo necesitan.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20.jpeg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"652\" data-id=\"94073\" src=\"https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20-1024x652.jpeg\" alt=\"\" class=\"wp-image-94073\" srcset=\"https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20-1024x652.jpeg 1024w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20-300x191.jpeg 300w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20-768x489.jpeg 768w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20-696x443.jpeg 696w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20-1068x680.jpeg 1068w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20-660x420.jpeg 660w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20.jpeg 1363w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.21-1.jpeg\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"94077\" src=\"https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.21-1-1024x683.jpeg\" alt=\"\" class=\"wp-image-94077\" srcset=\"https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.21-1-1024x683.jpeg 1024w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.21-1-300x200.jpeg 300w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.21-1-768x512.jpeg 768w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.21-1-1536x1024.jpeg 1536w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.21-1-696x464.jpeg 696w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.21-1-1068x712.jpeg 1068w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.21-1-630x420.jpeg 630w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.21-1.jpeg 1599w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.21-2.jpeg\"><img decoding=\"async\" width=\"1024\" height=\"617\" data-id=\"94075\" src=\"https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.21-2-1024x617.jpeg\" alt=\"\" class=\"wp-image-94075\" srcset=\"https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.21-2-1024x617.jpeg 1024w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.21-2-300x181.jpeg 300w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.21-2-768x463.jpeg 768w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.21-2-696x420.jpeg 696w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.21-2-1068x644.jpeg 1068w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.21-2-697x420.jpeg 697w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.21-2.jpeg 1460w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.21.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"655\" data-id=\"94074\" src=\"https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.21-1024x655.jpeg\" alt=\"\" class=\"wp-image-94074\" srcset=\"https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.21-1024x655.jpeg 1024w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.21-300x192.jpeg 300w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.21-768x491.jpeg 768w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.21-696x445.jpeg 696w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.21-1068x683.jpeg 1068w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.21-657x420.jpeg 657w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.21.jpeg 1417w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.22-1.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"94076\" src=\"https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.22-1-1024x683.jpeg\" alt=\"\" class=\"wp-image-94076\" srcset=\"https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.22-1-1024x683.jpeg 1024w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.22-1-300x200.jpeg 300w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.22-1-768x512.jpeg 768w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.22-1-1536x1024.jpeg 1536w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.22-1-696x464.jpeg 696w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.22-1-1068x712.jpeg 1068w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.22-1-630x420.jpeg 630w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.22-1.jpeg 1599w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.22.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"670\" data-id=\"94072\" src=\"https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.22-1024x670.jpeg\" alt=\"\" class=\"wp-image-94072\" srcset=\"https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.22-1024x670.jpeg 1024w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.22-300x196.jpeg 300w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.22-768x502.jpeg 768w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.22-1536x1005.jpeg 1536w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.22-696x455.jpeg 696w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.22-1068x699.jpeg 1068w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.22-642x420.jpeg 642w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.22-741x486.jpeg 741w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.22.jpeg 1564w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Feria del Libro En el marco de la XXIII Feria del Libro de La Rioja, el Ministerio de Salud present\u00f3 los avances del Plan Provincial de Salud 2030 a trav\u00e9s de la conferencia \u00abLa humanizaci\u00f3n del dato para transformar la gesti\u00f3n p\u00fablica\u00bb, un espacio de intercambio en el que se expusieron las estrategias que se [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":94073,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[12],"tags":[],"class_list":["post-94071","post","type-post","status-publish","format-standard","has-post-thumbnail","category-local"],"featured_image_urls":{"full":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20.jpeg",1363,868,false],"thumbnail":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20-150x150.jpeg",150,150,true],"medium":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20-300x191.jpeg",300,191,true],"medium_large":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20-768x489.jpeg",696,443,true],"large":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20-1024x652.jpeg",696,443,true],"1536x1536":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20.jpeg",1363,868,false],"2048x2048":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20.jpeg",1363,868,false],"td_218x150":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20-218x150.jpeg",218,150,true],"td_324x400":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20-324x400.jpeg",324,400,true],"td_485x360":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20-485x360.jpeg",485,360,true],"td_696x0":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20-696x443.jpeg",696,443,true],"td_1068x0":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20-1068x680.jpeg",1068,680,true],"td_1920x0":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20.jpeg",1363,868,false],"td_0x420":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20-660x420.jpeg",660,420,true],"td_80x60":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20-80x60.jpeg",80,60,true],"td_100x70":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20-100x70.jpeg",100,70,true],"td_265x198":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20-265x198.jpeg",265,198,true],"td_324x160":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20-324x160.jpeg",324,160,true],"td_324x235":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20-324x235.jpeg",324,235,true],"td_356x220":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20-356x220.jpeg",356,220,true],"td_356x364":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20-356x364.jpeg",356,364,true],"td_533x261":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20-533x261.jpeg",533,261,true],"td_534x462":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20-534x462.jpeg",534,462,true],"td_696x385":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20-696x385.jpeg",696,385,true],"td_741x486":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20-741x486.jpeg",741,486,true],"td_1068x580":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-20.00.20-1068x580.jpeg",1068,580,true]},"author_info":{"info":["RadioLaRioja"]},"category_info":"<a href=\"https:\/\/radiolarioja.com.ar\/rlr\/category\/local\/\" rel=\"category tag\">Local<\/a>","tag_info":"Local","comment_count":"0","_links":{"self":[{"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/posts\/94071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/comments?post=94071"}],"version-history":[{"count":1,"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/posts\/94071\/revisions"}],"predecessor-version":[{"id":94078,"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/posts\/94071\/revisions\/94078"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/media\/94073"}],"wp:attachment":[{"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/media?parent=94071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/categories?post=94071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/tags?post=94071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}