{"id":94058,"date":"2026-07-14T19:57:15","date_gmt":"2026-07-14T22:57:15","guid":{"rendered":"https:\/\/radiolarioja.com.ar\/rlr\/?p=94058"},"modified":"2026-07-14T19:57:16","modified_gmt":"2026-07-14T22:57:16","slug":"informan-nuevos-horarios-del-parque-el-saladillo","status":"publish","type":"post","link":"https:\/\/radiolarioja.com.ar\/rlr\/informan-nuevos-horarios-del-parque-el-saladillo\/","title":{"rendered":"Informan nuevos horarios del Parque \u201cEl Saladillo\u201d"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Abrir\u00e1 sus puertas a partir de las 8.00 y hasta las 19.00.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde esta semana, el Parque Natural y Arqueol\u00f3gico abrir\u00e1 sus puertas a partir de las 8.00 y hasta las 19.00 en horario corrido de lunes a lunes, para recibir a los visitantes riojanos y de todo el pa\u00eds que quieran conocer uno de los sitios patrimoniales m\u00e1s sorprendentes de La Rioja.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El valor de las entradas al parque es de 3.000 pesos para los turistas de todo el pa\u00eds, mientras que los visitantes de nuestra provincia pagan 1.500 pesos. Cabe se\u00f1alar que al tratarse del per\u00edodo de receso del personal, se cobrar\u00e1 entrada durante todos los d\u00edas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hace unos 2.000 a\u00f1os, el territorio que se conoce como Saladillo, estaba habitado por familias amplias (clanes), que se asentaron en el lugar en forma permanente. Dispusieron de nuevas tecnolog\u00edas como la cer\u00e1mica, los textiles y el tallado en piedra que permit\u00edan sostener grupos sociales, aunque reducidos. No ten\u00edan jefes permanentes ni jerarquizaci\u00f3n social. Cada grupo estaba separado del otro por unos cientos de metros. Los viviendas (casas pozo) se encontraban sobre peque\u00f1as lomadas, poco visibles, y la vida familiar se desarrollaba en el exterior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ubicaci\u00f3n respond\u00eda a la disponibilidad de recursos, sobre todo del agua, lo que los hizo muy h\u00e1biles en tecnolog\u00eda hidr\u00e1ulica (canales, represas). Las zonas de cultivo se inundaban con las crecidas de los r\u00edos que aportaban humedad, y se cultivaba principalmente ma\u00edz, tomate, man\u00ed, porotos y zapallo. Al pi\u00e9 de la sierra, en el llano, encontraban algarrobos y cha\u00f1ares, especies aut\u00f3ctonas de reconocido valor nutricional, y en las zonas altas abundaba la caza. Combinaban el modo de vida agr\u00edcola y pastoril con las pr\u00e1cticas de recolecci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Saladillo vivieron casi un centenar de personas esclavizadas por el color de su piel, sometidos, considerados animales, sin ning\u00fan derecho, trabajando de sol a sol para producir riquezas para sus due\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En \u00e9poca de la Independencia, casi el 50% de la poblaci\u00f3n de La Rioja eran \u201cnegros\u201d africanos, mientras que los pueblos originarios que hab\u00edan sido maltratados y diezmados no llegaban al 20%. En ese contexto, el mayor proceso de mestizaje se produjo entre europeos y africanos, dando como resultado lo que hoy somos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El papel de la comunidad afrodescendiente en la historia de La Rioja fue sistem\u00e1ticamente invisibilizado durante siglos. Aunque las contribuciones de las personas de origen africano fueron esenciales en campos como la m\u00fasica, la agricultura, el comercio y la integraci\u00f3n de las montoneras federales, su narrativa qued\u00f3 relegada en el discurso hist\u00f3rico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy, Saladillo trabaja por reivindicar las historias que durante tanto tiempo permanecieron en las sombras, en reconocimiento a la riqueza cultural y el rol constitutivo de la poblaci\u00f3n afrodescendiente en la identidad riojana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre el lugar<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Quebrada est\u00e1 ubicada sobre la ladera oriental del cord\u00f3n oriental del Velasco, a 20 km de la ciudad de La Rioja. Se trata de la primera casa que aparece con este estilo en La Rioja, que tiene s\u00f3tano y estufa a le\u00f1a, con techo plano en un sistema constructivo que se hab\u00eda inventado 20 a\u00f1os antes en Londres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los aspectos documentados en este lugar, es la presencia de los pueblos originarios con familias ampliadas que ocupaban espacios separadas por unos 200 metros y que se dedicaban a la caza y a la recolecci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La casa impact\u00f3 mucho en la poblaci\u00f3n por la forma que tiene, luego viene el terremoto 1894 y la reconstrucci\u00f3n de La Rioja se hace en base a este estilo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, en esta zona se instalaron los Jesuitas, que en su tarea evangelizadora, educadora y productiva, construyeron una estancia que se dedicaba a la fabricaci\u00f3n de cal, tinajas y tejas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La familia Luna Olmos construy\u00f3 una casona que se hizo sobre las ruinas de la estancia. En esa casona fue a vivir un ingeniero franc\u00e9s junto a su hija, que muri\u00f3 en El Saladillo enferma de tuberculosis. Si bien el ingeniero lleg\u00f3 a La Rioja para investigar la factibilidad de unir Catamarca y La Rioja a trav\u00e9s del ferrocarril y trabajar en la explotaci\u00f3n de la cal, la presencia de esta familia dej\u00f3 una intrigante leyenda, ya que los pobladores de la zona todav\u00eda escuchan las dulces canciones en idioma extranjero que cantaba la joven que muri\u00f3 en este sitio. Entre los inmensos valores hist\u00f3rico de este lugar, se encuentran las visitas que el ilustre Joaqu\u00edn V. Gonz\u00e1lez realizaba al Saladillo, por ser una propiedad de la familia de su esposa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cabe recordar que La Rioja sostiene una pol\u00edtica tur\u00edstica basada en la planificaci\u00f3n estrat\u00e9gica y la construcci\u00f3n colectiva a trav\u00e9s del denominado PlanTur La Rioja 360.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/images-68.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"678\" height=\"452\" src=\"https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/images-68.jpg\" alt=\"\" class=\"wp-image-94059\" style=\"width:1068px;height:auto\" srcset=\"https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/images-68.jpg 678w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/images-68-300x200.jpg 300w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/images-68-630x420.jpg 630w\" sizes=\"(max-width: 678px) 100vw, 678px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Abrir\u00e1 sus puertas a partir de las 8.00 y hasta las 19.00. Desde esta semana, el Parque Natural y Arqueol\u00f3gico abrir\u00e1 sus puertas a partir de las 8.00 y hasta las 19.00 en horario corrido de lunes a lunes, para recibir a los visitantes riojanos y de todo el pa\u00eds que quieran conocer uno de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":94059,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[12],"tags":[],"class_list":["post-94058","post","type-post","status-publish","format-standard","has-post-thumbnail","category-local"],"featured_image_urls":{"full":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/images-68.jpg",678,452,false],"thumbnail":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/images-68-150x150.jpg",150,150,true],"medium":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/images-68-300x200.jpg",300,200,true],"medium_large":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/images-68.jpg",678,452,false],"large":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/images-68.jpg",678,452,false],"1536x1536":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/images-68.jpg",678,452,false],"2048x2048":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/images-68.jpg",678,452,false],"td_218x150":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/images-68-218x150.jpg",218,150,true],"td_324x400":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/images-68-324x400.jpg",324,400,true],"td_485x360":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/images-68-485x360.jpg",485,360,true],"td_696x0":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/images-68.jpg",678,452,false],"td_1068x0":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/images-68.jpg",678,452,false],"td_1920x0":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/images-68.jpg",678,452,false],"td_0x420":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/images-68-630x420.jpg",630,420,true],"td_80x60":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/images-68-80x60.jpg",80,60,true],"td_100x70":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/images-68-100x70.jpg",100,70,true],"td_265x198":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/images-68-265x198.jpg",265,198,true],"td_324x160":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/images-68-324x160.jpg",324,160,true],"td_324x235":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/images-68-324x235.jpg",324,235,true],"td_356x220":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/images-68-356x220.jpg",356,220,true],"td_356x364":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/images-68-356x364.jpg",356,364,true],"td_533x261":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/images-68-533x261.jpg",533,261,true],"td_534x462":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/images-68-534x452.jpg",534,452,true],"td_696x385":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/images-68-678x385.jpg",678,385,true],"td_741x486":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/images-68.jpg",678,452,false],"td_1068x580":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/07\/images-68.jpg",678,452,false]},"author_info":{"info":["RadioLaRioja"]},"category_info":"<a href=\"https:\/\/radiolarioja.com.ar\/rlr\/category\/local\/\" rel=\"category tag\">Local<\/a>","tag_info":"Local","comment_count":"0","_links":{"self":[{"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/posts\/94058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/comments?post=94058"}],"version-history":[{"count":1,"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/posts\/94058\/revisions"}],"predecessor-version":[{"id":94060,"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/posts\/94058\/revisions\/94060"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/media\/94059"}],"wp:attachment":[{"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/media?parent=94058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/categories?post=94058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/tags?post=94058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}