{"id":91177,"date":"2026-05-12T21:50:41","date_gmt":"2026-05-13T00:50:41","guid":{"rendered":"https:\/\/radiolarioja.com.ar\/rlr\/?p=91177"},"modified":"2026-05-12T21:50:42","modified_gmt":"2026-05-13T00:50:42","slug":"el-gobierno-nacional-recorto-78-mil-millones-en-educacion-a-horas-de-la-marcha-universitaria","status":"publish","type":"post","link":"https:\/\/radiolarioja.com.ar\/rlr\/el-gobierno-nacional-recorto-78-mil-millones-en-educacion-a-horas-de-la-marcha-universitaria\/","title":{"rendered":"El gobierno nacional recort\u00f3 $78 mil millones en educaci\u00f3n a horas de la marcha universitaria"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/05\/2026-03-09-milei.webp\"><img fetchpriority=\"high\" decoding=\"async\" width=\"642\" height=\"428\" src=\"https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/05\/2026-03-09-milei.webp\" alt=\"\" class=\"wp-image-91179\" srcset=\"https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/05\/2026-03-09-milei.webp 642w, https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/05\/2026-03-09-milei-300x200.webp 300w\" sizes=\"(max-width: 642px) 100vw, 642px\" \/><\/a><figcaption class=\"wp-element-caption\">El gobierno de Milei vuelve a pasar la motosierra en educaci\u00f3n<\/figcaption><\/figure>\n\n\n\n<p>El ajuste afecta alfabetizaci\u00f3n, salarios docentes, becas y obras en universidades nacionales. La medida se oficializ\u00f3 en la previa a una nueva protesta federal.<\/p>\n\n\n\n<p>Horas antes de que se realice una nueva Marcha Federal Universitaria en todo el pa\u00eds, el gobierno de Javier Milei oficializ\u00f3 un recorte de casi $79 mil millones en distintas \u00e1reas educativas, incluyendo programas de alfabetizaci\u00f3n, becas estudiantiles, salarios docentes e infraestructura universitaria.<\/p>\n\n\n\n<p>La medida qued\u00f3 formalizada mediante la Decisi\u00f3n Administrativa 20\/2026 y volvi\u00f3 a profundizar el conflicto entre el Ejecutivo nacional y el sistema universitario, que este martes volver\u00e1 a movilizarse para reclamar financiamiento y recomposici\u00f3n salarial.<\/p>\n\n\n\n<p>En Rosario, la protesta tendr\u00e1 una fuerte convocatoria de estudiantes, docentes y trabajadores universitarios de la UNR y otros sectores educativos.<\/p>\n\n\n\n<p><strong>El principal recorte: alfabetizaci\u00f3n y salarios docentes<br><\/strong>La mayor poda presupuestaria impact\u00f3 sobre el Plan Nacional de Alfabetizaci\u00f3n, que perdi\u00f3 m\u00e1s de $35.288 millones destinados a transferencias para las provincias.<\/p>\n\n\n\n<p>El ajuste tambi\u00e9n elimin\u00f3 el Fondo de Compensaci\u00f3n Salarial Docente, utilizado para equilibrar salarios m\u00ednimos entre provincias, con una reducci\u00f3n cercana a los $9 mil millones.<\/p>\n\n\n\n<p>A eso se suman: $21.686 millones menos para infraestructura escolar y equipamiento, $6.649 millones de recorte en programas socioeducativos, m\u00e1s de $559 millones menos en becas estudiantiles y una reducci\u00f3n de $48 mil millones en transferencias para Educ.ar.<\/p>\n\n\n\n<p>La decisi\u00f3n se conoce adem\u00e1s en un contexto de fuerte deterioro salarial docente. Seg\u00fan datos difundidos recientemente por Conadu, los salarios universitarios acumulan una p\u00e9rdida real del 34,2% desde noviembre de 2023.<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/05\/El-gobierno-nacional-recorto-78-mil-millones-en-educacion-a-horas-de-la-marcha-universitaria.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incrustado de El gobierno nacional recort\u00f3 $78 mil millones en educaci\u00f3n a horas de la marcha universitaria.\"><\/object><a id=\"wp-block-file--media-426f45d7-76f3-46aa-bd7e-e1c69b468afa\" href=\"https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/05\/El-gobierno-nacional-recorto-78-mil-millones-en-educacion-a-horas-de-la-marcha-universitaria.pdf\">El gobierno nacional recort\u00f3 $78 mil millones en educaci\u00f3n a horas de la marcha universitaria<\/a><a href=\"https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/05\/El-gobierno-nacional-recorto-78-mil-millones-en-educacion-a-horas-de-la-marcha-universitaria.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-426f45d7-76f3-46aa-bd7e-e1c69b468afa\">Descarga<\/a><\/div>\n\n\n\n<p><br><strong>Universidades: obras frenadas y menos presupuesto<br><\/strong>El ajuste tambi\u00e9n golpe\u00f3 directamente a las universidades nacionales. La resoluci\u00f3n oficial elimin\u00f3 $5.303 millones destinados a infraestructura universitaria y dej\u00f3 paralizadas obras en trece casas de estudio.<\/p>\n\n\n\n<p>Entre las universidades m\u00e1s afectadas aparecen:<\/p>\n\n\n\n<p>Universidad Nacional de La Plata: -$1.043 millones<br>Universidad Nacional de General San Mart\u00edn: -$700 millones<br>Universidad Nacional de Avellaneda: -$700 millones<br>Universidad Nacional de R\u00edo Cuarto: -$680 millones<br>Universidad Nacional de Entre R\u00edos: -$540 millones<br>Aunque la Universidad Nacional de Rosario no aparece entre las principales afectadas en ese listado, el sistema universitario en general atraviesa una ca\u00edda presupuestaria sostenida.<\/p>\n\n\n\n<p>Seg\u00fan estimaciones del Centro de Econom\u00eda Pol\u00edtica Argentina (Cepa), el presupuesto universitario acumula una ca\u00edda real del 32,5% entre 2023 y 2025.<\/p>\n\n\n\n<p><strong>El trasfondo del conflicto universitario<br><\/strong>La discusi\u00f3n se da en medio del reclamo por la ley de financiamiento universitario, aprobada por el Congreso y luego vetada parcialmente por el gobierno nacional.<\/p>\n\n\n\n<p>Desde universidades, gremios docentes y centros de estudiantes sostienen que la norma buscaba recomponer parte del presupuesto perdido frente a la inflaci\u00f3n y garantizar funcionamiento b\u00e1sico de las casas de estudio.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><\/blockquote>\n\n\n\n<p>Seg\u00fan el Cepa, si esa ley se hubiera aplicado plenamente, el presupuesto universitario alcanzar\u00eda los $8,49 billones a valores de 2026, muy por encima de los recursos actualmente previstos.<\/p>\n\n\n\n<p>El proyecto impulsado por el Ejecutivo, en cambio, consolidar\u00eda un presupuesto aproximadamente 35% inferior al que hubiese correspondido con la ley aprobada por el Congreso.<\/p>\n\n\n\n<p><strong>Qu\u00e9 dice el gobierno<br><\/strong>Desde el oficialismo sostienen que la ley de financiamiento universitario no puede aplicarse por cuestiones presupuestarias y legales. El subsecretario de Pol\u00edticas Universitarias, Alejandro \u00c1lvarez, asegur\u00f3 que la norma qued\u00f3 \u201cimpl\u00edcitamente derogada\u201d al aprobarse el presupuesto y argument\u00f3 que implicar\u00eda un aumento salarial \u201cque el Estado no est\u00e1 en condiciones de afrontar\u201d.<\/p>\n\n\n\n<p>La postura oficial contrasta con la de rectores, sindicatos y organizaciones estudiantiles, que denuncian un ajuste estructural sobre el sistema universitario p\u00fablico.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ajuste afecta alfabetizaci\u00f3n, salarios docentes, becas y obras en universidades nacionales. La medida se oficializ\u00f3 en la<\/p>\n","protected":false},"author":2,"featured_media":91179,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-91177","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"featured_image_urls":{"full":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/05\/2026-03-09-milei.webp",642,428,false],"thumbnail":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/05\/2026-03-09-milei-150x150.webp",150,150,true],"medium":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/05\/2026-03-09-milei-300x200.webp",300,200,true],"medium_large":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/05\/2026-03-09-milei.webp",640,427,false],"large":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/05\/2026-03-09-milei.webp",640,427,false],"1536x1536":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/05\/2026-03-09-milei.webp",642,428,false],"2048x2048":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/05\/2026-03-09-milei.webp",642,428,false],"morenews-large":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/05\/2026-03-09-milei.webp",642,428,false],"morenews-medium":["https:\/\/radiolarioja.com.ar\/rlr\/wp-content\/uploads\/2026\/05\/2026-03-09-milei-590x410.webp",590,410,true]},"author_info":{"info":["RadioLaRioja"]},"category_info":"<a href=\"https:\/\/radiolarioja.com.ar\/rlr\/category\/nacional\/\" rel=\"category tag\">Nacional<\/a>","tag_info":"Nacional","comment_count":"0","_links":{"self":[{"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/posts\/91177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/comments?post=91177"}],"version-history":[{"count":1,"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/posts\/91177\/revisions"}],"predecessor-version":[{"id":91180,"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/posts\/91177\/revisions\/91180"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/media\/91179"}],"wp:attachment":[{"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/media?parent=91177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/categories?post=91177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolarioja.com.ar\/rlr\/wp-json\/wp\/v2\/tags?post=91177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}